{"id":10135,"date":"2026-03-03T15:51:47","date_gmt":"2026-03-03T07:51:47","guid":{"rendered":"https:\/\/loongsurfaces.com\/?post_type=product&#038;p=10135"},"modified":"2026-03-03T15:57:45","modified_gmt":"2026-03-03T07:57:45","slug":"contemporary-nordic-minimalist-living-room-natural-coffee-table-wholesale-cafe-shop-tea-desk-modern-coffee-table","status":"publish","type":"product","link":"https:\/\/loongsurfaces.com\/es\/producto\/contemporary-nordic-minimalist-living-room-natural-coffee-table-wholesale-cafe-shop-tea-desk-modern-coffee-table\/","title":{"rendered":"Contemporary Nordic Minimalist Living Room Natural Coffee Table Wholesale Cafe Shop Tea Desk Modern Coffee Table"},"content":{"rendered":"<div class=\"row\"  id=\"row-1123100996\">\n\n\t<div id=\"col-1584239877\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Bridge-Cutter-.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Bridge-Cutter-.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Bridge-Cutter--510x264.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Cortadora de puente CNC de 5 ejes<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-6d8ae69 elementor-widget elementor-widget-text-editor\" data-id=\"6d8ae69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Con todas las ventajas de una cortadora de puente normal, esta cortadora de puente CNC de 5 ejes puede hacer algo m\u00e1s. El cabezal de corte puede moverse 360 grados, lo que le permite cortar cualquier forma irregular, formas redondas, curvas y bordes biselados. Con su sistema computarizado y cabezal flexible, esta m\u00e1quina de corte CNC cuenta con la ventaja de una estructura compacta, alta precisi\u00f3n y eficiencia, y f\u00e1cil operaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1686322010\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"334\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Water-Jet-.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Water-Jet-.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-5-axis-CNC-Water-Jet--510x284.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-0b1d530 elementor-widget elementor-widget-heading\" data-id=\"0b1d530\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1quina CNC de 5 ejes con chorro de agua<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-71ed0cc elementor-widget elementor-widget-text-editor\" data-id=\"71ed0cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>El Water Jet se utiliza para cortar piedras con una l\u00ednea de agua delgada que contiene polvos met\u00e1licos finos bombeados desde una bomba de alta presi\u00f3n. Con el sistema computarizado y 5 ejes, el cabezal de corte puede moverse en todas las direcciones y es un cortador discontinuo. Es un Water Jet CNC multifuncional con alta precisi\u00f3n y varios \u00e1ngulos de corte, lo que lo convierte en el m\u00e1s \u00f3ptimo para hacer mosaicos y azulejos de formas irregulares.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2123133333\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-CNC-Router-p2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-CNC-Router-p2.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-CNC-Router-p2-510x264.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-87bf37b elementor-widget elementor-widget-heading\" data-id=\"87bf37b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Fresadora CNC<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-c2d9edb elementor-widget elementor-widget-text-editor\" data-id=\"c2d9edb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>La fresadora CNC es una fresadora controlada por ordenador para m\u00e1rmoles y piedras que puede realizar cortes en forma de hundimiento, tallados planos y tallados huecos en superficies de piedra. La estructura de puente de carga pesada garantiza una alta estabilidad, mientras que el sistema de doble cabezal ofrece el doble de rendimiento. Presenta alta velocidad de funcionamiento, alta precisi\u00f3n y estabilidad.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1252393967\">\n\n\t<div id=\"col-1758331545\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"360\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Automatic-Edge-Polisher-.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Automatic-Edge-Polisher-.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Automatic-Edge-Polisher--510x306.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-182fc1f elementor-widget elementor-widget-heading\" data-id=\"182fc1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Pulidora de cantos autom\u00e1tica<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-7b5254c elementor-widget elementor-widget-text-editor\" data-id=\"7b5254c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>La pulidora de bordes autom\u00e1tica se utiliza para pulir los bordes suavizados o los bordes redondeados peque\u00f1os de las encimeras de m\u00e1rmol, granito y piedra de cuarzo con una eficiencia y estabilidad superaltas. Est\u00e1 equipada con 13 cabezales de pulido que van desde granos gruesos hasta finos, lo que garantiza bordes pulidos de alta calidad. Es completamente autom\u00e1tica con una velocidad de funcionamiento estable, por lo que el resultado del pulido es muy estable.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-316423162\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"333\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Irregular-Profile-Miller-.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Irregular-Profile-Miller-.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/stone-factory-Irregular-Profile-Miller--510x283.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-f875a5c elementor-widget elementor-widget-heading\" data-id=\"f875a5c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-9382d19 elementor-widget elementor-widget-heading\" data-id=\"9382d19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Perfil irregular Miller<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-2f6ea6d elementor-widget elementor-widget-text-editor\" data-id=\"2f6ea6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>El fresador de perfiles irregulares se utiliza para crear y pulir de forma tosca los perfiles irregulares de piedras naturales y artificiales. Con la ayuda de esta herramienta, se puede lograr cualquier tipo de perfil irregular con un resultado estable y de alta calidad.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-275730370\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"361\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/Round-Table-Cutter-.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/Round-Table-Cutter-.jpg 600w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/Round-Table-Cutter--510x307.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-5998824 elementor-widget elementor-widget-heading\" data-id=\"5998824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-9a7ee48 elementor-widget elementor-widget-heading\" data-id=\"9a7ee48\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\">Cortador de mesa redondo<\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-d6f1100 elementor-widget elementor-widget-text-editor\" data-id=\"d6f1100\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Esta m\u00e1quina cortadora est\u00e1 especialmente dise\u00f1ada para cortar mesas redondas con una mesa giratoria y un cabezal de corte fijo. El di\u00e1metro de trabajo de la mesa var\u00eda de 500 mm a 1800 mm. Es completamente autom\u00e1tica para obtener el resultado m\u00e1s estable y calificado.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-512851061\">\n\n\t<div id=\"col-1098836636\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h1 style=\"text-align: center;\">Centrado en la venta al por mayor y proyectos de piedra con 15 a\u00f1os de experiencia<\/h1>\n<p style=\"text-align: center;\">Loong Stone, formado por un equipo joven de participantes vibrantes y creativos relacionados con la piedra que se han dedicado al m\u00e1rmol, granito, \u00f3nix, piedra artificial, superficies de cuarzo, terrazo, mosaicos de m\u00e1rmol y piedra sinterizada durante 15 a\u00f1os, es su socio comercial m\u00e1s confiable para la l\u00ednea completa de soluciones de piedra.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1806419911\">\n\n\t<div id=\"col-1683367329\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h1 class=\"pt-section-main-title\"><span style=\"font-size: 130%;\">L\u00edderes en soluciones de piedra de calidad<\/span><\/h1>\n<p class=\"pt-section-description\">Loong Stone es un fabricante y exportador de las mejores piedras naturales y artificiales, que ofrece la mayor selecci\u00f3n de losas de primera calidad y proyectos prefabricados, incluidos m\u00e1rmol, \u00f3nix, granito, piedra de cuarzo, m\u00e1rmol artificial, terrazo y piedra sinterizada, as\u00ed como soporte de certificaci\u00f3n. Como expertos en piedras de alta calidad, hemos estado sirviendo al mercado global durante a\u00f1os.<\/p>\n<h3 class=\"elementor-icon-box-title\">El mejor servicio de calidad<\/h3>\n<p>Suministramos diversas piedras en China, desde piedra natural hasta piedra artificial.<\/p>\n<ul>\n<li>Apoya tus elecciones y proyecta m\u00e1s opciones.<\/li>\n<li>Proyectos comerciales soluciones integrales de piedra.<\/li>\n<li>Disponibilidad de bloques, losas y baldosas de primera calidad.<\/li>\n<li>Para ahorrar tiempo y dinero a los clientes.<\/li>\n<\/ul>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1715250304\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"200\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Stone-Wholesale-Manufacturers-Price-choose-someone-color-what-want-for-someone-home-min.png\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1715250304 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1715250304 {\n    width: 68%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-387442775\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-default box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1083\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company.jpg 1000w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company-510x552.jpg 510w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company-369x400.jpg 369w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company-739x800.jpg 739w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-stone-factory-Chinese-stone-manufacturer-China-stone-exporter-stone-trading-company-768x832.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-left\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<a data-animate=\"fadeInLeft\" class=\"button secondary is-outline is-large lowercase\"  >\n\t\t<span>Leer m\u00e1s<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h3 class=\"et_pb_toggle_title\">How to pack and load ?<\/h3>\n<ul>\n<li>Outside with seaworthy strong fumigated wooden crate.<\/li>\n<li>Inside with soft plastic foam bewteen each vanity top, this package is for cut to size hotel or apartment project.<\/li>\n<li>Strong cartton box with plastic and wooden package for vanity top, this package is for supermarket or online store.<\/li>\n<\/ul>\n<div class=\"et_pb_toggle_content clearfix\">\n<ul>\n<li>Fumigated wooden bundles as frame packing;<\/li>\n<li>Strengthen with steel bar and plate;<\/li>\n<li>Wooden bars reinforce each bundle;<\/li>\n<li>8-15 pieces per bundle, 7-10 bundles per 20ft container;<\/li>\n<li>Small quantity: plywood with strong wooden bundle;<\/li>\n<\/ul>\n<\/div>\n<div class=\"row\"  id=\"row-1021146609\">\n\n\t<div id=\"col-1421574468\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_254179978\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"250\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1.jpg 1400w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1-510x128.jpg 510w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1-800x200.jpg 800w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1-768x192.jpg 768w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/China-Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-1-18x5.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_254179978 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1980132090\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"250\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory.jpg 1400w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-510x128.jpg 510w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-800x200.jpg 800w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-768x192.jpg 768w, https:\/\/loongsurfaces.com\/wp-content\/uploads\/Stone-Factory-Company-\u2013-Natural-StoneChina-Natural-Stone-and-Artifical-Stone-Factory-18x5.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1980132090 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-254533028\">\n\n\t<div id=\"col-1871667875\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Frequently Asked Questions<\/span><b><\/b><\/h3><\/div>\n<h3 class=\"lead\">Please read our FAQ before sending us a message.<strong>Email Us<\/strong>:\u00a0<a href=\"mailto:info@loongsurfaces.com\">info@loongsurfaces.com<\/a><\/h3>\n<div class=\"accordion\">\n\t<div id=\"accordion-132711022\" class=\"accordion-item\">\n\t\t<a id=\"accordion-132711022-label\" class=\"accordion-title plain\" href=\"#accordion-item-1,-do-you-have-a-minimum-order-quantity?\" aria-expanded=\"false\" aria-controls=\"accordion-132711022-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>1, Do You Have A Minimum Order Quantity?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-132711022-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-132711022-label\" >\n\t\t\t\n<p>We keep very little stock for products we promote or no stock. We do have a MOQ requirement to start the production. The MOQ varies by the Technics\u00a0and machinery. Normally, it is around 0.5 pallet or 1 pallet per item. Please feel free to contact our sale team to check more information.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1271201672\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1271201672-label\" class=\"accordion-title plain\" href=\"#accordion-item-2.-is-your-company-the-factory-or-trade-company?\" aria-expanded=\"false\" aria-controls=\"accordion-1271201672-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>2. Is your company the factory or trade company?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1271201672-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1271201672-label\" >\n\t\t\t\n<p>Our company has our own production facilities both in YunFu and FoShan city, and a sales center in Foshan city. We have very strong R&amp;D team and strict QC team, which guarantees the most stable quality for all products. We try our best to offer the most competitive price, high quality and best service.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-693859724\" class=\"accordion-item\">\n\t\t<a id=\"accordion-693859724-label\" class=\"accordion-title plain\" href=\"#accordion-item-3.-do-you-have-dealer-in-my-area?\" aria-expanded=\"false\" aria-controls=\"accordion-693859724-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>3. Do You Have Dealer In My Area?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-693859724-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-693859724-label\" >\n\t\t\t\n<p>we are professional OEM mosaic tile supplier in China for many different tile brands from around the world. It may be an importer in your country already carries the same products from our site with their own brand. Please feel free to advise your location and check with our sale team.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n<div class=\"accordion\">\n\t<div id=\"accordion-101738017\" class=\"accordion-item\">\n\t\t<a id=\"accordion-101738017-label\" class=\"accordion-title plain\" href=\"#accordion-item-4,-what-is-your-quality-and-assurance?\" aria-expanded=\"false\" aria-controls=\"accordion-101738017-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>4, What Is Your Quality And Assurance?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-101738017-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-101738017-label\" >\n\t\t\t\n<p>Loong mosaic tiles are manufactured in compliance with the strict quality standard in the industry. It is too said that we keep a top-level quality in the industry. Please feel free to ask our sale team for a free sample or visit us to check our quality.<\/p>\n<p>We are committed to continuously improve our products quality and responsible for quality problems. We provide free replacement or refund for any shipment with quality problems.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1200420294\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1200420294-label\" class=\"accordion-title plain\" href=\"#accordion-item-5,-what-is-your-lead-time?\" aria-expanded=\"false\" aria-controls=\"accordion-1200420294-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>5, What Is Your Lead Time?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1200420294-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1200420294-label\" >\n\t\t\t\n<p>From 2 to 4 weeks. It varies by qualities of your order, normally one 20\u201dGP container order are shipped within 4 weeks.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2387036491\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2387036491-label\" class=\"accordion-title plain\" href=\"#accordion-item-6,-what-is-your-sample-policy\" aria-expanded=\"false\" aria-controls=\"accordion-2387036491-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>6, What Is Your Sample Policy<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2387036491-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2387036491-label\" >\n\t\t\t\n<p>we provide free sample for oversea customer. It is generally shipped by UPS, DHL, FedEx, TNT.<\/p>\n<p>You are requested to arrange the picking up at our office if you have a international express account.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n<div class=\"accordion\">\n\t<div id=\"accordion-1660802718\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1660802718-label\" class=\"accordion-title plain\" href=\"#accordion-item-7.-what-payment-methods-your-company-accept?\" aria-expanded=\"false\" aria-controls=\"accordion-1660802718-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>7. What Payment Methods Your Company Accept?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1660802718-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1660802718-label\" >\n\t\t\t\n<p>We accept T\/T, L\/C, PayPal &amp; Western Union and other methods.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3621461687\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3621461687-label\" class=\"accordion-title plain\" href=\"#accordion-item-8,-can-you-make-customized-mail-express-gifts-box-with-my-own-logo?\" aria-expanded=\"false\" aria-controls=\"accordion-3621461687-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>8, Can You Make Customized Mail Express Gifts Box with My Own Logo?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3621461687-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3621461687-label\" >\n\t\t\t\n<p>Yes, we accept both OEM &amp; ODM order. You should issue an authorized letter to allow us to print your official logo on the gift carton box and other packages.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1989306123\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-two\">\n<h3><span class=\"Y2IQFc\" lang=\"en\">ENV\u00cdANOS UN MENSAJE<\/span><\/h3>\n<p><span style=\"text-align: var(--text-align);\">Obtenga el precio de f\u00e1brica ahora<br \/>\n\u00bfEst\u00e1 interesado en obtener m\u00e1s informaci\u00f3n sobre oportunidades de asociaci\u00f3n o en obtener una cotizaci\u00f3n? Complete el formulario a continuaci\u00f3n o cont\u00e1ctenos directamente. \u00a1Nuestro equipo est\u00e1 listo para ayudarlo!<\/span><\/p>\n<\/div>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8752-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"8752\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/product\/10135#wpcf7-f8752-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/product\/10135#wpcf7-f8752-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8752\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8752-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-flat\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su nombre (obligatorio)\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su correo electr\u00f3nico (obligatorio)\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tels\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Tu Tel (Opcional)\" value=\"\" type=\"tel\" name=\"your-tels\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Para obtener el mejor resultado, recomendamos incluir los siguientes detalles: - Presentaci\u00f3n personal - Art\u00edculos o servicios requeridos - Cantidad requerida\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p>Consultor\u00eda de negocios:*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required wpcf7-exclusive-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"checkbox\" value=\"Quotation\" \/><span class=\"wpcf7-list-item-label\">Cotizaci\u00f3n<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"checkbox\" value=\"Catalog\" \/><span class=\"wpcf7-list-item-label\">Catalogar<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"checkbox\" value=\"Service Support\" \/><span class=\"wpcf7-list-item-label\">Soporte de servicio<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"checkbox\" value=\"Project\" \/><span class=\"wpcf7-list-item-label\">Proyecto<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"checkbox\" value=\"I am interested in becoming an agent\" \/><span class=\"wpcf7-list-item-label\">Estoy interesado en convertirme en agente<\/span><\/label><\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" type=\"submit\" value=\"Entregar\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\n<div class=\"social-icons follow-icons\" ><a href=\"https:\/\/www.facebook.com\/loongsurfaces\" target=\"_blank\" data-label=\"Facebook\" class=\"icon primary button circle facebook tooltip\" title=\"S\u00edguenos en Facebook\" aria-label=\"S\u00edguenos en Facebook\" rel=\"noopener nofollow\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"https:\/\/www.instagram.com\/loongsurfaces\/\" target=\"_blank\" data-label=\"Instagram\" class=\"icon primary button circle instagram tooltip\" title=\"S\u00edguenos en Instagram\" aria-label=\"S\u00edguenos en Instagram\" rel=\"noopener nofollow\"><i class=\"icon-instagram\" ><\/i><\/a><a href=\"https:\/\/www.tiktok.com\/@loongsurfaces\" target=\"_blank\" data-label=\"TikTok\" class=\"icon primary button circle tiktok tooltip\" title=\"S\u00edguenos en TikTok\" aria-label=\"S\u00edguenos en TikTok\" rel=\"noopener nofollow\"><i class=\"icon-tiktok\" ><\/i><\/a><a href=\"https:\/\/twitter.com\/loongsurfaces\" data-label=\"Twitter\" target=\"_blank\" class=\"icon primary button circle twitter tooltip\" title=\"S\u00edguenos en Twitter\" aria-label=\"S\u00edguenos en Twitter\" rel=\"noopener nofollow\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"https:\/\/www.pinterest.com\/loongsurfaces\" data-label=\"Pinterest\" target=\"_blank\" class=\"icon primary button circle pinterest tooltip\" title=\"S\u00edguenos en Pinterest\" aria-label=\"S\u00edguenos en Pinterest\" rel=\"noopener nofollow\"><i class=\"icon-pinterest\" ><\/i><\/a><a href=\"https:\/\/www.linkedin.com\/company\/loongsurfaces\" data-label=\"LinkedIn\" target=\"_blank\" class=\"icon primary button circle linkedin tooltip\" title=\"S\u00edguenos en LinkedIn\" aria-label=\"S\u00edguenos en LinkedIn\" rel=\"noopener nofollow\"><i class=\"icon-linkedin\" ><\/i><\/a><a href=\"https:\/\/www.youtube.com\/@loongsurfaces\" data-label=\"YouTube\" target=\"_blank\" class=\"icon primary button circle youtube tooltip\" title=\"S\u00edguenos en Youtube\" aria-label=\"S\u00edguenos en Youtube\" rel=\"noopener nofollow\"><i class=\"icon-youtube\" ><\/i><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<table style=\"height: 289px;\" width=\"417\">\n<tbody>\n<tr>\n<td width=\"127\">Brand\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">LOONG STONE<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Material\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">Mable<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">SKU\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">SS-003<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Color\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">Green<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Product:<\/td>\n<td style=\"text-align: left;\" width=\"405\">\n<div>Table<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Size\uff08mm\uff09\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">2600x900mm<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Thickness(mm)<\/td>\n<td style=\"text-align: left;\" width=\"405\">Customized<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Finish Type\uff1a<\/td>\n<td style=\"text-align: left;\" width=\"405\">Polished<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Application:<\/td>\n<td style=\"text-align: left;\" width=\"405\">Living room<\/td>\n<\/tr>\n<tr>\n<td width=\"127\">Origin:<\/td>\n<td style=\"text-align: left;\" width=\"405\">China<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t<a class=\"paoc-popup-click paoc-popup-cust-6537 paoc-popup-button paoc-popup-btn\" href=\"javascript:void(0);\">Contact  US<\/a>\r\n\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/api.whatsapp.com\/send?phone=8617708695534\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6536\" src=\"https:\/\/loongsurfaces.com\/wp-content\/uploads\/2022\/11\/WhatsApp-8613902807851.png\" alt=\"\" width=\"150\" height=\"35\" \/><\/a><\/p>","protected":false},"featured_media":10124,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[76,180,106,121,167,173,174,175],"product_tag":[],"class_list":{"0":"post-10135","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-products","7":"product_cat-furniture-marble-granite","8":"product_cat-marble-stone","9":"product_cat-premium-collections","10":"product_cat-reliable-works","11":"product_cat-stone-countertop","12":"product_cat-stone-craftworks","13":"product_cat-stone-furniture","15":"first","16":"instock","17":"shipping-taxable","18":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/product\/10135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/media\/10124"}],"wp:attachment":[{"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/media?parent=10135"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/product_brand?post=10135"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/product_cat?post=10135"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/loongsurfaces.com\/es\/wp-json\/wp\/v2\/product_tag?post=10135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}